{"id":9034,"date":"2025-06-02T13:14:09","date_gmt":"2025-06-02T10:14:09","guid":{"rendered":"https:\/\/jak.fi\/asiakastarinat\/jak-200r-faellgreifer-fuer-avant-radlader\/"},"modified":"2025-06-02T13:16:09","modified_gmt":"2025-06-02T10:16:09","slug":"jak-200r-faellgreifer-fuer-avant-radlader","status":"publish","type":"customer","link":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/","title":{"rendered":"JAK-200R F\u00e4llgreifer f\u00fcr AVANT Radlader"},"content":{"rendered":"\n<p>Tuomo Tuominen, ein Unternehmer aus Lappeenranta, berichtet von positiven Erfahrungen mit dem JAK-200R F\u00e4llgreifer, der an seinem AVANT Radlader installiert ist. Der F\u00e4llgreifer hat es ihm erm\u00f6glicht, seine eigenen Holzressourcen auf effizientere und sicherere Weise zu nutzen. <\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg\" alt=\"JAK-200R F&#xE4;llgreifer, angebaut an Avant Radlader\" class=\"wp-image-8561\" srcset=\"https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg 1000w, https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13-700x467.jpg 700w, https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13-768x512.jpg 768w, https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13-800x534.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\"><strong>Effiziente Nutzung von Holz aus Ihrem eigenen Wald &#8211; die L\u00f6sung im JAK F\u00e4llgreifer<\/strong><\/h3>\n\n<p>Tuominens Unternehmen, <a href=\"https:\/\/tuomisenklapijarengas.fi\/fi\" target=\"_blank\" rel=\"noreferrer noopener\">Tuominen Klapi&amp;Rengas<\/a>, ben\u00f6tigt jedes Jahr eine gro\u00dfe Menge an Holzsp\u00e4nen f\u00fcr sein eigenes Hackschnitzelheizwerk. Fr\u00fcher wurde das Holz von au\u00dfen gekauft, aber jetzt wird es aus den eigenen W\u00e4ldern und von Stra\u00dfenr\u00e4ndern gesammelt. <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u201eWir haben uns f\u00fcr den JAK-Energiegrabber entschieden, weil er mit einem passenden Adapter direkt an den AVANT angeschlossen werden kann. Das war ein gro\u00dfer Vorteil gegen\u00fcber der Konkurrenz\u201c,<\/em> sagt Tuominen.<\/p>\n<\/blockquote>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-09.jpg\" alt=\"JAK-200R F&#xE4;llgreifer, angebaut an Avant Radlader\" class=\"wp-image-9012\" srcset=\"https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-09.jpg 1000w, https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-09-700x467.jpg 700w, https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-09-768x512.jpg 768w, https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-09-800x534.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\"><strong>Warum JAK-200R? Kompatibilit\u00e4t und ein Massensammler brachten die L\u00f6sung <\/strong><\/h3>\n\n<p>Ein wichtiger Faktor f\u00fcr den Import war, dass der JAK-200R F\u00e4llgreifer fertig f\u00fcr einen radlader geliefert wurde. Das sparte Zeit und M\u00fche &#8211; eine separate Montage war nicht erforderlich. <\/p>\n\n<p>Ein weiterer gro\u00dfer Vorteil war der Massensammler, der das Sammeln von St\u00f6cken und St\u00e4mmen in B\u00fcndeln anstelle von einzelnen B\u00e4umen erm\u00f6glicht.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u201eMit einem B\u00fcndelstapler k\u00f6nnen Sie problemlos gro\u00dfe B\u00fcndel erhalten, die sich leichter zum Lagerort transportieren lassen\u201c, sagt Tuominen.<\/em> sagt Tuominen.<\/p>\n<\/blockquote>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-04.jpg\" alt=\"JAK-200R F&#xE4;llgreifer, angebaut an Avant Radlader\" class=\"wp-image-9018\" srcset=\"https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-04.jpg 1000w, https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-04-700x467.jpg 700w, https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-04-768x512.jpg 768w, https:\/\/jak.fi\/wp-content\/uploads\/2025\/06\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-04-800x534.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\"><strong>Hervorragende Klingengestaltung und Betriebssicherheit<\/strong><\/h3>\n\n<p>Das Klingenmodell JAK-200R ist f\u00fcr praktische Aufgaben konzipiert: Es muss nicht immer an einer bestimmten Stelle der Klinge Holz schneiden, sondern kann auf beiden Seiten der Klinge geschnitten werden. Das erleichtert vor allem die Beseitigung von dichtem Gestr\u00fcpp. <\/p>\n\n<p>Au\u00dferdem spielte der Sicherheitsaspekt eine gro\u00dfe Rolle. Bei der Arbeit auf der Stra\u00dfe ist die Arbeit in einer AVANT-Kabine sicherer als zum Beispiel die Arbeit mit einer Kreiss\u00e4ge. <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u201eSie k\u00f6nnten die gleiche Arbeit mit einer Kreiss\u00e4ge erledigen, aber das ist nicht so sicher &#8211; in der Kabine des Radladers sind Sie vor dem Verkehr sicher\u201c, sagt Tuominen.<\/em> sagt Tuominen.<\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\">Der <strong>JAK F\u00e4llgreifer ist eine erfolgreiche Wahl<\/strong> f\u00fcr den AVANT Radlader<\/h3>\n\n<p>Nach ein paar Wochen des Einsatzes sind Tuominens Erfahrungen sehr positiv. Die Gr\u00f6\u00dfe und Leistung des JAK-200R passt gut zum AVANT-Radlader und die Arbeit ist m\u00fchelos. <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>&#8222;Der F\u00e4llgreifer hat die richtige Gr\u00f6\u00dfe und kann einen ausreichend gro\u00dfen Baum f\u00e4llen. Sch\u00f6ne B\u00fcndel lassen sich leicht erstellen&#8220;,&#8220;<\/em> res\u00fcmiert Tuomo.<\/p>\n<\/blockquote>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Miksi valitsin JAK energiakouran AVANT py\u00f6r\u00e4kuormaajaan?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/tbklLROWQzA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<h3 class=\"wp-block-heading\"><strong>Zusammenfassung: Der JAK-200R F\u00e4llgreifer f\u00fcr einen radlader ist eine effiziente und sichere Wahl<\/strong><\/h3>\n\n<p>Die Geschichte von Tuomo Tuominen zeigt, wie der richtige F\u00e4llgreifer das Sammeln von Brennholz effizienter machen, die Sicherheit verbessern und langfristig Kosten sparen kann. Der JAK F\u00e4llgreifer f\u00fcr AVANT-Maschinen ist eine einfache und effektive L\u00f6sung f\u00fcr die Forstwirtschaft und die R\u00e4umung von Stra\u00dfenr\u00e4ndern. <\/p>\n\n<h4 class=\"wp-block-heading\"><strong>M\u00f6chten Sie mehr erfahren?<\/strong><\/h4>\n\n<p>Informieren Sie sich <a href=\"https:\/\/jak.fi\/de\/produkte\/fallgreifer-fur-radlader-teleskoplader\/jak-200r-gen4-faellgreifer-fuer-radlader-und-teleskoplader\/\">HIER<\/a> \u00fcber den JAK-200R F\u00e4llgreifer oder kontaktieren Sie uns &#8211; wir helfen Ihnen gerne bei der Auswahl des richtigen Greifers f\u00fcr Ihre Bed\u00fcrfnisse!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tuomo Tuominen, ein Unternehmer aus Lappeenranta, berichtet von positiven Erfahrungen mit dem JAK-200R F\u00e4llgreifer, der an seinem AVANT Radlader installiert ist. Der F\u00e4llgreifer hat es ihm erm\u00f6glicht, seine eigenen Holzressourcen auf effizientere und sicherere Weise zu nutzen. Effiziente Nutzung von Holz aus Ihrem eigenen Wald &#8211; die L\u00f6sung im JAK F\u00e4llgreifer Tuominens Unternehmen, Tuominen Klapi&amp;Rengas, [&hellip;]<\/p>\n","protected":false},"featured_media":8564,"template":"","class_list":["post-9034","customer","type-customer","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JAK-200R F\u00e4llgreifer f\u00fcr AVANT Radlader &#8211; JAK-Metalli Oy<\/title>\n<meta name=\"description\" content=\"Tuomo Tuominen berichtet \u00fcber seine Erfahrungen mit dem JAK-200R F\u00e4llgreifer an einem AVANT Radlader. Lesen Sie, warum gerade dieser Energiegreifer gew\u00e4hlt wurde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JAK-200R F\u00e4llgreifer f\u00fcr AVANT Radlader &#8211; JAK-Metalli Oy\" \/>\n<meta property=\"og:description\" content=\"Tuomo Tuominen berichtet \u00fcber seine Erfahrungen mit dem JAK-200R F\u00e4llgreifer an einem AVANT Radlader. Lesen Sie, warum gerade dieser Energiegreifer gew\u00e4hlt wurde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/\" \/>\n<meta property=\"og:site_name\" content=\"JAK-Metalli Oy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jaktreeshears\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-02T10:16:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/kundengeschichten\\\/jak-200r-faellgreifer-fuer-avant-radlader\\\/\",\"url\":\"https:\\\/\\\/jak.fi\\\/de\\\/kundengeschichten\\\/jak-200r-faellgreifer-fuer-avant-radlader\\\/\",\"name\":\"JAK-200R F\u00e4llgreifer f\u00fcr AVANT Radlader &#8211; JAK-Metalli Oy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/kundengeschichten\\\/jak-200r-faellgreifer-fuer-avant-radlader\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/kundengeschichten\\\/jak-200r-faellgreifer-fuer-avant-radlader\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jak.fi\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg\",\"datePublished\":\"2025-06-02T10:14:09+00:00\",\"dateModified\":\"2025-06-02T10:16:09+00:00\",\"description\":\"Tuomo Tuominen berichtet \u00fcber seine Erfahrungen mit dem JAK-200R F\u00e4llgreifer an einem AVANT Radlader. Lesen Sie, warum gerade dieser Energiegreifer gew\u00e4hlt wurde.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/kundengeschichten\\\/jak-200r-faellgreifer-fuer-avant-radlader\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jak.fi\\\/de\\\/kundengeschichten\\\/jak-200r-faellgreifer-fuer-avant-radlader\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/kundengeschichten\\\/jak-200r-faellgreifer-fuer-avant-radlader\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jak.fi\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg\",\"contentUrl\":\"https:\\\/\\\/jak.fi\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg\",\"width\":1000,\"height\":667,\"caption\":\"JAK-200R F\u00e4llgreifer, angebaut an Avant Radlader\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/kundengeschichten\\\/jak-200r-faellgreifer-fuer-avant-radlader\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/jak.fi\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kundengeschichten\",\"item\":\"https:\\\/\\\/jak.fi\\\/de\\\/kundengeschichten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JAK-200R F\u00e4llgreifer f\u00fcr AVANT Radlader\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/jak.fi\\\/de\\\/\",\"name\":\"JAK-Metalli Oy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/#organization\"},\"alternateName\":\"JAK Tree shears\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jak.fi\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/#organization\",\"name\":\"JAK-Metalli Oy\",\"alternateName\":\"JAK Tree shears\",\"url\":\"https:\\\/\\\/jak.fi\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jak.fi\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/JAK-logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jak.fi\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/JAK-logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"JAK-Metalli Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/jak.fi\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jaktreeshears\",\"https:\\\/\\\/www.instagram.com\\\/jaktreeshears\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCAwvaVhBBkPie8MeAGbdY1w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JAK-200R F\u00e4llgreifer f\u00fcr AVANT Radlader &#8211; JAK-Metalli Oy","description":"Tuomo Tuominen berichtet \u00fcber seine Erfahrungen mit dem JAK-200R F\u00e4llgreifer an einem AVANT Radlader. Lesen Sie, warum gerade dieser Energiegreifer gew\u00e4hlt wurde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/","og_locale":"de_DE","og_type":"article","og_title":"JAK-200R F\u00e4llgreifer f\u00fcr AVANT Radlader &#8211; JAK-Metalli Oy","og_description":"Tuomo Tuominen berichtet \u00fcber seine Erfahrungen mit dem JAK-200R F\u00e4llgreifer an einem AVANT Radlader. Lesen Sie, warum gerade dieser Energiegreifer gew\u00e4hlt wurde.","og_url":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/","og_site_name":"JAK-Metalli Oy","article_publisher":"https:\/\/www.facebook.com\/jaktreeshears","article_modified_time":"2025-06-02T10:16:09+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/","url":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/","name":"JAK-200R F\u00e4llgreifer f\u00fcr AVANT Radlader &#8211; JAK-Metalli Oy","isPartOf":{"@id":"https:\/\/jak.fi\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/#primaryimage"},"image":{"@id":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/#primaryimage"},"thumbnailUrl":"https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg","datePublished":"2025-06-02T10:14:09+00:00","dateModified":"2025-06-02T10:16:09+00:00","description":"Tuomo Tuominen berichtet \u00fcber seine Erfahrungen mit dem JAK-200R F\u00e4llgreifer an einem AVANT Radlader. Lesen Sie, warum gerade dieser Energiegreifer gew\u00e4hlt wurde.","breadcrumb":{"@id":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/#primaryimage","url":"https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg","contentUrl":"https:\/\/jak.fi\/wp-content\/uploads\/2024\/05\/JAK-200R-tree-shear-on-Avant-wheel-loader-web-13.jpg","width":1000,"height":667,"caption":"JAK-200R F\u00e4llgreifer, angebaut an Avant Radlader"},{"@type":"BreadcrumbList","@id":"https:\/\/jak.fi\/de\/kundengeschichten\/jak-200r-faellgreifer-fuer-avant-radlader\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/jak.fi\/de\/"},{"@type":"ListItem","position":2,"name":"Kundengeschichten","item":"https:\/\/jak.fi\/de\/kundengeschichten\/"},{"@type":"ListItem","position":3,"name":"JAK-200R F\u00e4llgreifer f\u00fcr AVANT Radlader"}]},{"@type":"WebSite","@id":"https:\/\/jak.fi\/de\/#website","url":"https:\/\/jak.fi\/de\/","name":"JAK-Metalli Oy","description":"","publisher":{"@id":"https:\/\/jak.fi\/de\/#organization"},"alternateName":"JAK Tree shears","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jak.fi\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/jak.fi\/de\/#organization","name":"JAK-Metalli Oy","alternateName":"JAK Tree shears","url":"https:\/\/jak.fi\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jak.fi\/de\/#\/schema\/logo\/image\/","url":"https:\/\/jak.fi\/wp-content\/uploads\/2024\/09\/JAK-logo-696x696-1.jpg","contentUrl":"https:\/\/jak.fi\/wp-content\/uploads\/2024\/09\/JAK-logo-696x696-1.jpg","width":696,"height":696,"caption":"JAK-Metalli Oy"},"image":{"@id":"https:\/\/jak.fi\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jaktreeshears","https:\/\/www.instagram.com\/jaktreeshears\/","https:\/\/www.youtube.com\/channel\/UCAwvaVhBBkPie8MeAGbdY1w"]}]}},"_links":{"self":[{"href":"https:\/\/jak.fi\/de\/wp-json\/wp\/v2\/customer\/9034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jak.fi\/de\/wp-json\/wp\/v2\/customer"}],"about":[{"href":"https:\/\/jak.fi\/de\/wp-json\/wp\/v2\/types\/customer"}],"version-history":[{"count":2,"href":"https:\/\/jak.fi\/de\/wp-json\/wp\/v2\/customer\/9034\/revisions"}],"predecessor-version":[{"id":9042,"href":"https:\/\/jak.fi\/de\/wp-json\/wp\/v2\/customer\/9034\/revisions\/9042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jak.fi\/de\/wp-json\/wp\/v2\/media\/8564"}],"wp:attachment":[{"href":"https:\/\/jak.fi\/de\/wp-json\/wp\/v2\/media?parent=9034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}